{"id":46913,"date":"2025-05-28T20:28:05","date_gmt":"2025-05-28T20:28:05","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/honda-hrx-476c-vy\/"},"modified":"2025-07-30T09:41:17","modified_gmt":"2025-07-30T09:41:17","slug":"honda-hrx-476c-vy","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/","title":{"rendered":"Honda HRX 476C VY"},"content":{"rendered":"<p>Si votre jardin est complexe et soigneusement am\u00e9nag\u00e9, la gamme premium Honda est faite pour vous. Si facile \u00e0 man\u0153uvrer et \u00e0 tourner, vous ne voudrez plus jamais revenir \u00e0 votre ancienne tondeuse. De plus, tous les mod\u00e8les sont \u00e9quip\u00e9s du syst\u00e8me de mulching r\u00e9glable Versamow. Vous obtenez ainsi une pelouse parfaite, quel que soit l&#8217;\u00e9tat de votre pelouse.<\/p>\n<p>Largeur de coupe\u00a0: 47\u00a0cm<br \/>\nMoteur\u00a0: GCVx 170<br \/>\nTransmission\u00a0: SMART Drive<br \/>\nCh\u00e2ssis\u00a0: Honda Polystrong (plastique)<br \/>\nKit mulching\u00a0: Syst\u00e8me de mulching s\u00e9lectif Versamow\u00ae<br \/>\nR\u00e9glage de la hauteur\u00a0: 7\u00a0positions variables<br \/>\nCaract\u00e9ristiques\u00a0: Starter automatique, arr\u00eat moteur, embrayage de lame<br \/>\nCapacit\u00e9 du bac de ramassage\u00a0: 69\u00a0litres<br \/>\nPoids \u00e0 vide\u00a0: 42\u00a0kg<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si votre jardin est complexe et soigneusement am\u00e9nag\u00e9, la gamme premium Honda est faite pour vous. Si facile \u00e0 man\u0153uvrer et \u00e0 tourner, vous ne voudrez plus jamais revenir \u00e0 votre ancienne tondeuse. De plus, tous les mod\u00e8les sont \u00e9quip\u00e9s du syst\u00e8me de mulching r\u00e9glable Versamow. Vous obtenez ainsi une pelouse parfaite, quel que soit [&hellip;]<\/p>\n","protected":false},"featured_media":38161,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[942,946,992,677],"product_tag":[],"class_list":["post-46913","product","type-product","status-publish","has-post-thumbnail","product_cat-tondeuses-a-essence","product_cat-tondeuses-a-essence-honda","product_cat-tondeuses-a-gazon-honda","product_cat-tondeuse","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Honda HRX 476C VY - Lambrechts Tuinmachines<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honda HRX 476C VY - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Si votre jardin est complexe et soigneusement am\u00e9nag\u00e9, la gamme premium Honda est faite pour vous. Si facile \u00e0 man\u0153uvrer et \u00e0 tourner, vous ne voudrez plus jamais revenir \u00e0 votre ancienne tondeuse. De plus, tous les mod\u00e8les sont \u00e9quip\u00e9s du syst\u00e8me de mulching r\u00e9glable Versamow. Vous obtenez ainsi une pelouse parfaite, quel que soit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T09:41:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HRX-476C-VY-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honda HRX 476C VY - Lambrechts Tuinmachines","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Honda HRX 476C VY - Lambrechts Tuinmachines","og_description":"Si votre jardin est complexe et soigneusement am\u00e9nag\u00e9, la gamme premium Honda est faite pour vous. Si facile \u00e0 man\u0153uvrer et \u00e0 tourner, vous ne voudrez plus jamais revenir \u00e0 votre ancienne tondeuse. De plus, tous les mod\u00e8les sont \u00e9quip\u00e9s du syst\u00e8me de mulching r\u00e9glable Versamow. Vous obtenez ainsi une pelouse parfaite, quel que soit [&hellip;]","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-07-30T09:41:17+00:00","og_image":[{"width":400,"height":373,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HRX-476C-VY-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/","name":"Honda HRX 476C VY - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HRX-476C-VY-.jpg","datePublished":"2025-05-28T20:28:05+00:00","dateModified":"2025-07-30T09:41:17+00:00","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HRX-476C-VY-.jpg","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HRX-476C-VY-.jpg","width":400,"height":373,"caption":"Honda HRX 476C VY"},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hrx-476c-vy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"Honda HRX 476C VY"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/46913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/46913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/38161"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=46913"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=46913"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=46913"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=46913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}