{"id":44735,"date":"2025-05-28T20:28:23","date_gmt":"2025-05-28T20:28:23","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/encore-48\/"},"modified":"2025-07-30T07:57:01","modified_gmt":"2025-07-30T07:57:01","slug":"encore-48","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/","title":{"rendered":"Encore 48"},"content":{"rendered":"<p>Les tondeuses Encore Edge offrent une coupe parfaite, m\u00eame dans les conditions les plus difficiles. Puissance et efficacit\u00e9\u00a0!<\/p>\n<p>Largeur de coupe\u00a0: 122\u00a0cm<br \/>\nMoteur\u00a0: Kawasaki FR691V 23\u00a0ch<br \/>\nTransmission\u00a0: Hydrostatique Hydro Gear ZT-3200<br \/>\nVitesse avant\u00a0: 14,5\u00a0km\/h<br \/>\nVitesse arri\u00e8re\u00a0: 7,7\u00a0km\/h<br \/>\nSyst\u00e8me de tonte\u00a0: 3\u00a0lames<br \/>\nKit mulching\u00a0: Int\u00e9gr\u00e9 de s\u00e9rie<br \/>\nCaract\u00e9ristiques\u00a0:<br \/>\nCapacit\u00e9 du bac de ramassage\u00a0:<br \/>\nVidange du bac de ramassage\u00a0:<br \/>\nCapacit\u00e9 du r\u00e9servoir d\u2019essence\u00a0: 36\u00a0litres<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les tondeuses Encore Edge offrent une coupe parfaite, m\u00eame dans les conditions les plus difficiles. Puissance et efficacit\u00e9\u00a0! Largeur de coupe\u00a0: 122\u00a0cm Moteur\u00a0: Kawasaki FR691V 23\u00a0ch Transmission\u00a0: Hydrostatique Hydro Gear ZT-3200 Vitesse avant\u00a0: 14,5\u00a0km\/h Vitesse arri\u00e8re\u00a0: 7,7\u00a0km\/h Syst\u00e8me de tonte\u00a0: 3\u00a0lames Kit mulching\u00a0: Int\u00e9gr\u00e9 de s\u00e9rie Caract\u00e9ristiques\u00a0: Capacit\u00e9 du bac de ramassage\u00a0: Vidange du bac [&hellip;]<\/p>\n","protected":false},"featured_media":73477,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[889,834],"product_tag":[],"class_list":["post-44735","product","type-product","status-publish","has-post-thumbnail","product_cat-debroussailleuses-tondeuses-tout-terrain","product_cat-tondeuses-tracteurs-autoportees","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encore 48 - Lambrechts Tuinmachines<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encore 48 - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Les tondeuses Encore Edge offrent une coupe parfaite, m\u00eame dans les conditions les plus difficiles. Puissance et efficacit\u00e9\u00a0! Largeur de coupe\u00a0: 122\u00a0cm Moteur\u00a0: Kawasaki FR691V 23\u00a0ch Transmission\u00a0: Hydrostatique Hydro Gear ZT-3200 Vitesse avant\u00a0: 14,5\u00a0km\/h Vitesse arri\u00e8re\u00a0: 7,7\u00a0km\/h Syst\u00e8me de tonte\u00a0: 3\u00a0lames Kit mulching\u00a0: Int\u00e9gr\u00e9 de s\u00e9rie Caract\u00e9ristiques\u00a0: Capacit\u00e9 du bac de ramassage\u00a0: Vidange du bac [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T07:57:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Encore-Edge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encore 48 - Lambrechts Tuinmachines","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Encore 48 - Lambrechts Tuinmachines","og_description":"Les tondeuses Encore Edge offrent une coupe parfaite, m\u00eame dans les conditions les plus difficiles. Puissance et efficacit\u00e9\u00a0! Largeur de coupe\u00a0: 122\u00a0cm Moteur\u00a0: Kawasaki FR691V 23\u00a0ch Transmission\u00a0: Hydrostatique Hydro Gear ZT-3200 Vitesse avant\u00a0: 14,5\u00a0km\/h Vitesse arri\u00e8re\u00a0: 7,7\u00a0km\/h Syst\u00e8me de tonte\u00a0: 3\u00a0lames Kit mulching\u00a0: Int\u00e9gr\u00e9 de s\u00e9rie Caract\u00e9ristiques\u00a0: Capacit\u00e9 du bac de ramassage\u00a0: Vidange du bac [&hellip;]","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-07-30T07:57:01+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Encore-Edge.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/","name":"Encore 48 - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Encore-Edge.jpg","datePublished":"2025-05-28T20:28:23+00:00","dateModified":"2025-07-30T07:57:01+00:00","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Encore-Edge.jpg","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Encore-Edge.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/encore-48\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"Encore 48"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/73477"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=44735"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=44735"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=44735"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=44735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}