{"id":44716,"date":"2025-05-28T20:28:17","date_gmt":"2025-05-28T20:28:17","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/honda-hf-2625-hm\/"},"modified":"2025-07-30T09:14:12","modified_gmt":"2025-07-30T09:14:12","slug":"honda-hf-2625-hm","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/","title":{"rendered":"Honda HF 2625 HM"},"content":{"rendered":"<p>Pour un entretien parfait de votre pelouse, vous appr\u00e9cierez sa largeur de coupe accrue, son confort optimal et ses performances sup\u00e9rieures. Nos moteurs bicylindre en V offrent une puissance et une fiabilit\u00e9 constantes, ainsi que des fonctionnalit\u00e9s telles qu&#8217;un indicateur sonore de bac plein et l&#8217;\u00e9jection \u00e9lectrique de l&#8217;herbe. L&#8217;engagement des lames en douceur et par simple pression sur une touche et la transmission hydrostatique vous permettent de tondre de grandes surfaces \u00e0 votre rythme pour des r\u00e9sultats parfaits.<\/p>\n<p>Largeur de coupe\u00a0: 122\u00a0cm<br \/>\nTransmission\u00a0: Hydrostatique<br \/>\nSyst\u00e8me de tonte\u00a0: 2\u00a0lames, \u00e9jection arri\u00e8re<br \/>\nSyst\u00e8me de tonte\u00a0: \u00c9lectromagn\u00e9tique<br \/>\nKit mulching\u00a0: Syst\u00e8me mulching Versamow\u00ae<br \/>\nR\u00e9glage de la hauteur\u00a0: Variable<br \/>\nCaract\u00e9ristiques\u00a0:<br \/>\nCapacit\u00e9 du bac de ramassage\u00a0: 350\u00a0litres<br \/>\nVidange du bac\u00a0: Manuelle<br \/>\nCapacit\u00e9 du r\u00e9servoir d&#8217;essence\u00a0: 8,5\u00a0litres<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour un entretien parfait de votre pelouse, vous appr\u00e9cierez sa largeur de coupe accrue, son confort optimal et ses performances sup\u00e9rieures. Nos moteurs bicylindre en V offrent une puissance et une fiabilit\u00e9 constantes, ainsi que des fonctionnalit\u00e9s telles qu&#8217;un indicateur sonore de bac plein et l&#8217;\u00e9jection \u00e9lectrique de l&#8217;herbe. L&#8217;engagement des lames en douceur et [&hellip;]<\/p>\n","protected":false},"featured_media":38392,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[834,929],"product_tag":[],"class_list":["post-44716","product","type-product","status-publish","has-post-thumbnail","product_cat-tondeuses-tracteurs-autoportees","product_cat-tracteurs-honda-tractor","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Honda HF 2625 HM - Lambrechts Tuinmachines<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honda HF 2625 HM - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Pour un entretien parfait de votre pelouse, vous appr\u00e9cierez sa largeur de coupe accrue, son confort optimal et ses performances sup\u00e9rieures. Nos moteurs bicylindre en V offrent une puissance et une fiabilit\u00e9 constantes, ainsi que des fonctionnalit\u00e9s telles qu&#8217;un indicateur sonore de bac plein et l&#8217;\u00e9jection \u00e9lectrique de l&#8217;herbe. L&#8217;engagement des lames en douceur et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T09:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HF-2625-HM-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1242\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honda HF 2625 HM - Lambrechts Tuinmachines","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Honda HF 2625 HM - Lambrechts Tuinmachines","og_description":"Pour un entretien parfait de votre pelouse, vous appr\u00e9cierez sa largeur de coupe accrue, son confort optimal et ses performances sup\u00e9rieures. Nos moteurs bicylindre en V offrent une puissance et une fiabilit\u00e9 constantes, ainsi que des fonctionnalit\u00e9s telles qu&#8217;un indicateur sonore de bac plein et l&#8217;\u00e9jection \u00e9lectrique de l&#8217;herbe. L&#8217;engagement des lames en douceur et [&hellip;]","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-07-30T09:14:12+00:00","og_image":[{"width":1242,"height":731,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HF-2625-HM-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/","name":"Honda HF 2625 HM - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HF-2625-HM-.jpg","datePublished":"2025-05-28T20:28:17+00:00","dateModified":"2025-07-30T09:14:12+00:00","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HF-2625-HM-.jpg","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Honda-HF-2625-HM-.jpg","width":1242,"height":731,"caption":"Honda HF 2625 HM"},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/honda-hf-2625-hm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"Honda HF 2625 HM"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/38392"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=44716"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=44716"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=44716"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=44716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}