{"id":44715,"date":"2025-05-28T20:28:18","date_gmt":"2025-05-28T20:28:18","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/batterie-stiga-estate-384e\/"},"modified":"2025-07-30T08:02:14","modified_gmt":"2025-07-30T08:02:14","slug":"batterie-stiga-estate-384e","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/","title":{"rendered":"Batterie Stiga ESTATE 384E"},"content":{"rendered":"<p>Le tracteur de pelouse Estate 384e allie parfaitement puissance et plaisir de conduite. Cette tondeuse autoport\u00e9e robuste est aliment\u00e9e par une puissante batterie STIGA de 30 Ah avec cellules Li-Ion haut de gamme, d\u00e9velopp\u00e9e et test\u00e9e par STIGA en Italie.<\/p>\n<p>Largeur de coupe\u00a0: 84 cm<br \/>\nBatterie lithium-ion 48 V 30 Ah<br \/>\nAutonomie\u00a0: Jusqu&#8217;\u00e0 3\u00a0000 m\u00b2<br \/>\nTemps de charge\u00a0: 2 heures<br \/>\nTransmission\u00a0: Propulsion<br \/>\nSyst\u00e8me de coupe\u00a0: 2 lames, \u00e9jection arri\u00e8re<br \/>\nR\u00e9glage de la hauteur\u00a0: Variable<br \/>\nCaract\u00e9ristiques\u00a0:<br \/>\nCapacit\u00e9 du bac de ramassage\u00a0: 240 litres<br \/>\nVidange du bac\u00a0: Manuelle<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le tracteur de pelouse Estate 384e allie parfaitement puissance et plaisir de conduite. Cette tondeuse autoport\u00e9e robuste est aliment\u00e9e par une puissante batterie STIGA de 30 Ah avec cellules Li-Ion haut de gamme, d\u00e9velopp\u00e9e et test\u00e9e par STIGA en Italie. Largeur de coupe\u00a0: 84 cm Batterie lithium-ion 48 V 30 Ah Autonomie\u00a0: Jusqu&#8217;\u00e0 3\u00a0000 m\u00b2 [&hellip;]<\/p>\n","protected":false},"featured_media":38416,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[834],"product_tag":[],"class_list":["post-44715","product","type-product","status-publish","has-post-thumbnail","product_cat-tondeuses-tracteurs-autoportees","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Batterie Stiga ESTATE 384E - Lambrechts Tuinmachines<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Batterie Stiga ESTATE 384E - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Le tracteur de pelouse Estate 384e allie parfaitement puissance et plaisir de conduite. Cette tondeuse autoport\u00e9e robuste est aliment\u00e9e par une puissante batterie STIGA de 30 Ah avec cellules Li-Ion haut de gamme, d\u00e9velopp\u00e9e et test\u00e9e par STIGA en Italie. Largeur de coupe\u00a0: 84 cm Batterie lithium-ion 48 V 30 Ah Autonomie\u00a0: Jusqu&#8217;\u00e0 3\u00a0000 m\u00b2 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-30T08:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Stiga-ESTATE-384E-Accu-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"949\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Batterie Stiga ESTATE 384E - Lambrechts Tuinmachines","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Batterie Stiga ESTATE 384E - Lambrechts Tuinmachines","og_description":"Le tracteur de pelouse Estate 384e allie parfaitement puissance et plaisir de conduite. Cette tondeuse autoport\u00e9e robuste est aliment\u00e9e par une puissante batterie STIGA de 30 Ah avec cellules Li-Ion haut de gamme, d\u00e9velopp\u00e9e et test\u00e9e par STIGA en Italie. Largeur de coupe\u00a0: 84 cm Batterie lithium-ion 48 V 30 Ah Autonomie\u00a0: Jusqu&#8217;\u00e0 3\u00a0000 m\u00b2 [&hellip;]","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-07-30T08:02:14+00:00","og_image":[{"width":949,"height":683,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Stiga-ESTATE-384E-Accu-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/","name":"Batterie Stiga ESTATE 384E - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Stiga-ESTATE-384E-Accu-.jpg","datePublished":"2025-05-28T20:28:18+00:00","dateModified":"2025-07-30T08:02:14+00:00","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Stiga-ESTATE-384E-Accu-.jpg","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/Stiga-ESTATE-384E-Accu-.jpg","width":949,"height":683,"caption":"Batterie Stiga ESTATE 384E"},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/batterie-stiga-estate-384e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"Batterie Stiga ESTATE 384E"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/38416"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=44715"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=44715"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=44715"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=44715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}