{"id":44457,"date":"2025-05-30T02:54:19","date_gmt":"2025-05-30T02:54:19","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/jo-beau-b31-110\/"},"modified":"2025-07-29T12:18:29","modified_gmt":"2025-07-29T12:18:29","slug":"jo-beau-b31-110","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/","title":{"rendered":"Jo Beau B31-110"},"content":{"rendered":"<p>Avec seulement 74 cm de large, la B31-110 est la dessoucheuse enti\u00e8rement automatique la plus compacte du march\u00e9. Gr\u00e2ce \u00e0 ses chenilles larges et \u00e0 son excellente maniabilit\u00e9, la B31 se d\u00e9place sans effort sur les terrains accident\u00e9s et les foss\u00e9s. Le puissant moteur essence Vanguard 2 cylindres de 31 ch broie une souche de 110 cm de large et 50 cm de profondeur en un temps record. Le bras de fraisage est actionn\u00e9 hydrauliquement, de mani\u00e8re enti\u00e8rement automatique ou manuelle, et peut \u00eatre relev\u00e9 en position verticale pour le transport. La roue de fraisage est entra\u00een\u00e9e par une double courroie trap\u00e9zo\u00efdale industrielle.<\/p>\n<p>Largeur de travail max. 1100 mm<br \/>\nMoteur : B&amp;S Vanguard 2 cylindres 31 ch<br \/>\nHauteur de fraisage max. 500 mm<br \/>\nProfondeur de fraisage max. 500 mm<br \/>\nD\u00e9bit max. Largeur de fraisage 1100 mm<br \/>\nFonctionnement : Enti\u00e8rement automatique<br \/>\nBrosse Greenteeth 700, 12 pi\u00e8ces, rotative \u00e0 120\u00b0 et r\u00e9aff\u00fbtable<br \/>\nTransmission du disque : Double courroie trap\u00e9zo\u00efdale industrielle<br \/>\nDiam\u00e8tre de la molette : 440 mm<br \/>\nPoids : 610 kg<br \/>\nCaract\u00e9ristiques : Larges rails pour une meilleure stabilit\u00e9, 3 anneaux de levage<\/p>\n<p>Les 12 burins Greenteeth\u00ae peuvent \u00eatre facilement tourn\u00e9s 3 fois (120\u00b0) puis aff\u00fbt\u00e9s. Le r\u00e9servoir de carburant m\u00e9tallique s\u00e9par\u00e9 \u00e9vite tout risque d&#8217;incendie lors du remplissage, ce qui souligne une fois de plus les normes de s\u00e9curit\u00e9 Jo Beau ! En bref : la B31-110 r\u00e9pond une fois de plus aux exigences des jardiniers professionnels, des arboristes et des loueurs qui n&#8217;h\u00e9sitent pas \u00e0 acc\u00e9der aux endroits difficiles d&#8217;acc\u00e8s. Toutes les machines Jo Beau sont fabriqu\u00e9es conform\u00e9ment aux directives europ\u00e9ennes en vigueur et sont certifi\u00e9es CE.<\/p>\n<p>Toutes les machines sont fournies avec un manuel et une liste de pi\u00e8ces d\u00e9tach\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec seulement 74 cm de large, la B31-110 est la dessoucheuse enti\u00e8rement automatique la plus compacte du march\u00e9. Gr\u00e2ce \u00e0 ses chenilles larges et \u00e0 son excellente maniabilit\u00e9, la B31 se d\u00e9place sans effort sur les terrains accident\u00e9s et les foss\u00e9s. Le puissant moteur essence Vanguard 2 cylindres de 31 ch broie une souche de [&hellip;]<\/p>\n","protected":false},"featured_media":44831,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[827,829],"product_tag":[],"class_list":["post-44457","product","type-product","status-publish","has-post-thumbnail","product_cat-broyeurs-de-souches","product_cat-jo-beau-fr-2","first","on_reserve","sale","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jo Beau B31-110 - Lambrechts Tuinmachines<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jo Beau B31-110 - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Avec seulement 74 cm de large, la B31-110 est la dessoucheuse enti\u00e8rement automatique la plus compacte du march\u00e9. Gr\u00e2ce \u00e0 ses chenilles larges et \u00e0 son excellente maniabilit\u00e9, la B31 se d\u00e9place sans effort sur les terrains accident\u00e9s et les foss\u00e9s. Le puissant moteur essence Vanguard 2 cylindres de 31 ch broie une souche de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T12:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/jo-beau-b31-110-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1015\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jo Beau B31-110 - Lambrechts Tuinmachines","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Jo Beau B31-110 - Lambrechts Tuinmachines","og_description":"Avec seulement 74 cm de large, la B31-110 est la dessoucheuse enti\u00e8rement automatique la plus compacte du march\u00e9. Gr\u00e2ce \u00e0 ses chenilles larges et \u00e0 son excellente maniabilit\u00e9, la B31 se d\u00e9place sans effort sur les terrains accident\u00e9s et les foss\u00e9s. Le puissant moteur essence Vanguard 2 cylindres de 31 ch broie une souche de [&hellip;]","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-07-29T12:18:29+00:00","og_image":[{"width":1015,"height":811,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/jo-beau-b31-110-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/","name":"Jo Beau B31-110 - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/jo-beau-b31-110-1-1.jpg","datePublished":"2025-05-30T02:54:19+00:00","dateModified":"2025-07-29T12:18:29+00:00","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/jo-beau-b31-110-1-1.jpg","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/jo-beau-b31-110-1-1.jpg","width":1015,"height":811,"caption":"jo beau b31-110"},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/jo-beau-b31-110\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"Jo Beau B31-110"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/44457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/44831"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=44457"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=44457"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=44457"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=44457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}