{"id":27610,"date":"2025-05-21T10:32:17","date_gmt":"2025-05-21T10:32:17","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/"},"modified":"2026-02-21T11:53:54","modified_gmt":"2026-02-21T11:53:54","slug":"stihl-scie-debranchage-pr-24-24-cm-305-g-fr","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/","title":{"rendered":"Scie d'\u00e9branchage PR 24, 24 cm, 305 g"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":71299,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[220,242,219],"product_tag":[580,1024,579,1022],"class_list":["post-27610","product","type-product","status-publish","has-post-thumbnail","product_cat-appareils-et-outils-fr","product_cat-scies-de-jardin-secateurs-coupe-branches-scies-a-branches-fr","product_cat-stihl-fr","product_tag-stihl","product_tag-stihl-fr","product_tag-syndified","product_tag-syndified-fr","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STIHL Scie d&#039;\u00e9branchage avec lame de scie droite pour un\u2026<\/title>\n<meta name=\"description\" content=\"STIHL Scie d&#039;\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d&#039;\u00e9branchage, PR24, PR33\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STIHL Scie d&#039;\u00e9branchage avec lame de scie droite pour une...\" \/>\n<meta property=\"og:description\" content=\"STIHL Scie d&#039;\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d&#039;\u00e9branchage, PR24, PR33\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-21T11:53:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"STIHL Scie d&#039;\u00e9branchage avec lame de scie droite pour une...\" \/>\n<meta name=\"twitter:description\" content=\"STIHL Scie d&#039;\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d&#039;\u00e9branchage, PR24, PR33\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STIHL Scie d'\u00e9branchage avec lame de scie droite pour un\u2026","description":"STIHL Scie d'\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d'\u00e9branchage, PR24, PR33","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"STIHL Scie d'\u00e9branchage avec lame de scie droite pour une...","og_description":"STIHL Scie d'\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d'\u00e9branchage, PR24, PR33","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2026-02-21T11:53:54+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"STIHL Scie d'\u00e9branchage avec lame de scie droite pour une...","twitter_description":"STIHL Scie d'\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d'\u00e9branchage, PR24, PR33","twitter_image":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/","name":"STIHL Scie d'\u00e9branchage avec lame de scie droite pour une...","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp","datePublished":"2025-05-21T10:32:17+00:00","dateModified":"2026-02-21T11:53:54+00:00","description":"STIHL Scie d'\u00e9branchage PR 24, 24 cm, 305 g par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Scie d'\u00e9branchage, PR24, PR33","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/12\/39374_Z-MEGACUT-S001-1.webp","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-scie-debranchage-pr-24-24-cm-305-g-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"Scie d&#8217;\u00e9branchage PR 24, 24 cm, 305 g"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/27610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/27610\/revisions"}],"predecessor-version":[{"id":62422,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/27610\/revisions\/62422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/71299"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=27610"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=27610"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=27610"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=27610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}