{"id":27260,"date":"2025-05-21T10:30:23","date_gmt":"2025-05-21T10:30:23","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/stihl-hse-81-60-cm-fr\/"},"modified":"2026-07-11T06:59:01","modified_gmt":"2026-07-11T06:59:01","slug":"stihl-hse-81-60-cm-fr","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/","title":{"rendered":"HSE 81, 60 cm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":54715,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[220,35,219,222,1008],"product_tag":[1024,580,1022,579],"class_list":["post-27260","product","type-product","status-publish","has-post-thumbnail","product_cat-appareils-et-outils-fr","product_cat-non-categorise","product_cat-stihl-fr","product_cat-taille-haies-taille-haies-sur-perche-fr","product_cat-taille-haies","product_tag-stihl-fr","product_tag-stihl","product_tag-syndified-fr","product_tag-syndified","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STIHL Taille-haie \u00e9lectrique HSE 81<\/title>\n<meta name=\"description\" content=\"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STIHL Taille-haie \u00e9lectrique HSE 81\" \/>\n<meta property=\"og:description\" content=\"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T06:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"STIHL Taille-haie \u00e9lectrique HSE 81\" \/>\n<meta name=\"twitter:description\" content=\"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STIHL Taille-haie \u00e9lectrique HSE 81","description":"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"STIHL Taille-haie \u00e9lectrique HSE 81","og_description":"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2026-07-11T06:59:01+00:00","og_image":[{"width":960,"height":367,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"STIHL Taille-haie \u00e9lectrique HSE 81","twitter_description":"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...","twitter_image":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/","name":"STIHL Taille-haie \u00e9lectrique HSE 81","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp","datePublished":"2025-05-21T10:30:23+00:00","dateModified":"2026-07-11T06:59:01+00:00","description":"STIHL HSE 81, 60 cm par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Taille-haie \u00e9lectrique robuste pour les haies \u00e0 gross...","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/09\/31199_H-HSE81-S007-3.webp","width":960,"height":367},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/produit\/stihl-hse-81-60-cm-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lambrechts.designstudio.net\/fr\/boutique-3\/"},{"@type":"ListItem","position":3,"name":"HSE 81, 60 cm"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/27260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/27260\/revisions"}],"predecessor-version":[{"id":62366,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product\/27260\/revisions\/62366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media\/54715"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=27260"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_brand?post=27260"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_cat?post=27260"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/product_tag?post=27260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}