{"id":1231,"date":"2025-05-21T09:05:46","date_gmt":"2025-05-21T09:05:46","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/stihl-fr\/appareils-et-outils-fr\/broyeurs-de-vegetaux-fr\/"},"modified":"2026-07-11T03:48:27","modified_gmt":"2026-07-11T03:48:27","slug":"broyeurs-de-vegetaux-fr","status":"publish","type":"page","link":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/","title":{"rendered":"Broyeurs de v\u00e9g\u00e9taux"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":43550,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1231","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STIHL Appareils et outils Broyeurs de v\u00e9g\u00e9taux<\/title>\n<meta name=\"description\" content=\"STIHL Broyeurs de v\u00e9g\u00e9taux par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Gr\u00e2ce aux broyeurs de branches STIHL, transfo...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STIHL Appareils et outils Broyeurs de v\u00e9g\u00e9taux\" \/>\n<meta property=\"og:description\" content=\"STIHL Broyeurs de v\u00e9g\u00e9taux par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Gr\u00e2ce aux broyeurs de branches STIHL, transfo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:48:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STIHL Appareils et outils Broyeurs de v\u00e9g\u00e9taux","description":"STIHL Broyeurs de v\u00e9g\u00e9taux par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Gr\u00e2ce aux broyeurs de branches STIHL, transfo...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"STIHL Appareils et outils Broyeurs de v\u00e9g\u00e9taux","og_description":"STIHL Broyeurs de v\u00e9g\u00e9taux par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Gr\u00e2ce aux broyeurs de branches STIHL, transfo...","og_url":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2026-07-11T03:48:27+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/","url":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/","name":"STIHL Appareils et outils Broyeurs de v\u00e9g\u00e9taux","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website"},"datePublished":"2025-05-21T09:05:46+00:00","dateModified":"2026-07-11T03:48:27+00:00","description":"STIHL Broyeurs de v\u00e9g\u00e9taux par Machines de Jardin Lambrechts \u00e0 Herent, Belgique et Tienen, Belgique. Gr\u00e2ce aux broyeurs de branches STIHL, transfo...","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/broyeurs-de-vegetaux-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Nettoyer","item":"https:\/\/lambrechts.designstudio.net\/fr\/nettoyer-fr\/"},{"@type":"ListItem","position":3,"name":"Broyeurs de v\u00e9g\u00e9taux"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/fr\/#website","url":"https:\/\/lambrechts.designstudio.net\/fr\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/pages\/1231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/comments?post=1231"}],"version-history":[{"count":1,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/pages\/1231\/revisions"}],"predecessor-version":[{"id":57649,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/pages\/1231\/revisions\/57649"}],"up":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/pages\/43550"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/fr\/wp-json\/wp\/v2\/media?parent=1231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}