{"id":27355,"date":"2025-05-21T10:30:53","date_gmt":"2025-05-21T10:30:53","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/"},"modified":"2026-05-02T09:52:27","modified_gmt":"2026-05-02T09:52:27","slug":"stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/","title":{"rendered":"HSA 140 T, 60 cm, zonder accu en lader"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":27356,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[973,400,402,399,16],"product_tag":[580,1025,579,1023],"class_list":["post-27355","product","type-product","status-publish","has-post-thumbnail","product_cat-hedge-trimmers","product_cat-equipment-and-tools-en","product_cat-hedge-trimmers-hedge-trimmers-on-a-pole-en","product_cat-stihl-en","product_cat-uncategorized","product_tag-stihl","product_tag-stihl-en","product_tag-syndified","product_tag-syndified-en","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STIHL HSA 140 T - Cordless hedge trimmer<\/title>\n<meta name=\"description\" content=\"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STIHL HSA 140 T - Cordless hedge trimmer\" \/>\n<meta property=\"og:description\" content=\"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T09:52:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"STIHL HSA 140 T - Cordless hedge trimmer\" \/>\n<meta name=\"twitter:description\" content=\"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STIHL HSA 140 T - Cordless hedge trimmer","description":"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"STIHL HSA 140 T - Cordless hedge trimmer","og_description":"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...","og_url":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2026-05-02T09:52:27+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"STIHL HSA 140 T - Cordless hedge trimmer","twitter_description":"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...","twitter_image":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/","url":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/","name":"STIHL HSA 140 T - Cordless hedge trimmer","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp","datePublished":"2025-05-21T10:30:53+00:00","dateModified":"2026-05-02T09:52:27+00:00","description":"STIHL HSA 140 T, 60 cm, zonder accu en lader by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. STIHL HSA 140 T cordless hedge trimm...","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/121593_HSA140T-750mm-EU_HQ_P_2024-03_0005-5.webp","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hsa-140-t-60-cm-zonder-accu-en-lader-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lambrechts.designstudio.net\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"HSA 140 T, 60 cm, zonder accu en lader"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product\/27355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product\/27355\/revisions"}],"predecessor-version":[{"id":62383,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product\/27355\/revisions\/62383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media\/27356"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=27355"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product_brand?post=27355"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product_cat?post=27355"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product_tag?post=27355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}