{"id":13207,"date":"2025-05-21T09:12:48","date_gmt":"2025-05-21T09:12:48","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/product\/stihl-hl-92-c-e\/"},"modified":"2026-05-02T07:20:23","modified_gmt":"2026-05-02T07:20:23","slug":"stihl-hl-92-c-e","status":"publish","type":"product","link":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/","title":{"rendered":"HL 92 C-E"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":13209,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[973,400,402,399],"product_tag":[1025,580,1023,579],"class_list":["post-13207","product","type-product","status-publish","has-post-thumbnail","product_cat-hedge-trimmers","product_cat-equipment-and-tools-en","product_cat-hedge-trimmers-hedge-trimmers-on-a-pole-en","product_cat-stihl-en","product_tag-stihl-en","product_tag-stihl","product_tag-syndified-en","product_tag-syndified","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STIHL HL 92 C-E - Thermal pole hedge trimmer<\/title>\n<meta name=\"description\" content=\"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STIHL HL 92 C-E - Thermal pole hedge trimmer\" \/>\n<meta property=\"og:description\" content=\"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T07:20:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"STIHL HL 92 C-E - Thermal pole hedge trimmer\" \/>\n<meta name=\"twitter:description\" content=\"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STIHL HL 92 C-E - Thermal pole hedge trimmer","description":"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"STIHL HL 92 C-E - Thermal pole hedge trimmer","og_description":"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...","og_url":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2026-05-02T07:20:23+00:00","og_image":[{"width":960,"height":1440,"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"STIHL HL 92 C-E - Thermal pole hedge trimmer","twitter_description":"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...","twitter_image":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/","url":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/","name":"STIHL HL 92 C-E - Thermal pole hedge trimmer","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp","datePublished":"2025-05-21T09:12:48+00:00","dateModified":"2026-05-02T07:20:23+00:00","description":"STIHL HL 92 C-E by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. Ideal for particularly wide high or long hedges ErgoStart easy-st...","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/05\/6312_H-HL92CE-D001-2.webp","width":960,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/product\/stihl-hl-92-c-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lambrechts.designstudio.net\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"HL 92 C-E"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product\/13207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product\/13207\/revisions"}],"predecessor-version":[{"id":59951,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product\/13207\/revisions\/59951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media\/13209"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=13207"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product_brand?post=13207"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product_cat?post=13207"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/product_tag?post=13207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}