{"id":48660,"date":"2025-08-01T14:26:14","date_gmt":"2025-08-01T14:26:14","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/tourex-en\/tourex-generators-en\/petrol-inverters-en\/"},"modified":"2025-10-09T11:10:59","modified_gmt":"2025-10-09T11:10:59","slug":"petrol-inverters-en","status":"publish","type":"page","link":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/","title":{"rendered":"Petrol Inverters"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":48652,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-48660","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tourex Tourex Generators Petrol Inverters<\/title>\n<meta name=\"description\" content=\"Tourex Petrol Inverters by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tourex Tourex Generators Petrol Inverters\" \/>\n<meta property=\"og:description\" content=\"Tourex Petrol Inverters by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T11:10:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tourex Tourex Generators Petrol Inverters","description":"Tourex Petrol Inverters by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Tourex Tourex Generators Petrol Inverters","og_description":"Tourex Petrol Inverters by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium.","og_url":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-10-09T11:10:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/","url":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/","name":"Tourex Tourex Generators Petrol Inverters","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"datePublished":"2025-08-01T14:26:14+00:00","dateModified":"2025-10-09T11:10:59+00:00","description":"Tourex Petrol Inverters by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium.","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/petrol-inverters-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Electricity and Water Supply","item":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/"},{"@type":"ListItem","position":3,"name":"Tourex Generators","item":"https:\/\/lambrechts.designstudio.net\/en\/electricity-and-water-supply-en\/tourex-generators-en\/"},{"@type":"ListItem","position":4,"name":"Petrol Inverters"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/48660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/comments?post=48660"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/48660\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/48652"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=48660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}