{"id":46661,"date":"2025-07-28T15:16:59","date_gmt":"2025-07-28T15:16:59","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/negri-garden-machines\/"},"modified":"2025-08-13T15:01:29","modified_gmt":"2025-08-13T15:01:29","slug":"negri-garden-machines","status":"publish","type":"page","link":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/","title":{"rendered":"Negri Garden Machines"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-46654 aligncenter\" src=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png\" alt=\"Negri Logo\" width=\"300\" height=\"150\" srcset=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png 300w, https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1-24x12.png 24w, https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1-36x18.png 36w, https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1-48x24.png 48w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Negri is a company that has specialized in the production of vegetable waste shredders, air machines and leaf vacuums for more than 30 years, for individuals and professionals.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Negri is a company that has specialized in the production of vegetable waste shredders, air machines and leaf vacuums for more than 30 years, for individuals and professionals.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-collections.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-46661","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Negri Garden Machines - Lambrechts Tuinmachines<\/title>\n<meta name=\"description\" content=\"Negri garden machines here and there, Belgium from Lambrechts Garden Machines.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Negri Garden Machines - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Negri garden machines here and there, Belgium from Lambrechts Garden Machines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T15:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Negri Garden Machines - Lambrechts Tuinmachines","description":"Negri garden machines here and there, Belgium from Lambrechts Garden Machines.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Negri Garden Machines - Lambrechts Tuinmachines","og_description":"Negri garden machines here and there, Belgium from Lambrechts Garden Machines.","og_url":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-08-13T15:01:29+00:00","og_image":[{"url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/","url":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/","name":"Negri Garden Machines - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png","datePublished":"2025-07-28T15:16:59+00:00","dateModified":"2025-08-13T15:01:29+00:00","description":"Negri garden machines here and there, Belgium from Lambrechts Garden Machines.","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/#primaryimage","url":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png","contentUrl":"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/negri-category-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/negri-garden-machines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Negri Garden Machines"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/46661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/comments?post=46661"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/46661\/revisions"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=46661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}