{"id":46574,"date":"2025-07-28T14:12:56","date_gmt":"2025-07-28T14:12:56","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/ambrogio-garden-machines\/"},"modified":"2025-08-13T15:02:18","modified_gmt":"2025-08-13T15:02:18","slug":"ambrogio-garden-machines","status":"publish","type":"page","link":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/","title":{"rendered":"Ambrogio Garden Machines"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-46566 aligncenter\" src=\"https:\/\/lambrechts-tuinmachines.be\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png\" alt=\"Ambrogio logo\" width=\"300\" height=\"150\" srcset=\"https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png 300w, https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1-24x12.png 24w, https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1-36x18.png 36w, https:\/\/lambrechts.designstudio.net\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1-48x24.png 48w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Research, innovation and sustainability.<br \/>\nAmbrogio robotic lawnmowers are entirely designed, manufactured and continuously implemented by Zucchetti Centro Sistemi SpA (ZCS).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Research, innovation and sustainability. Ambrogio robotic lawnmowers are entirely designed, manufactured and continuously implemented by Zucchetti Centro Sistemi SpA (ZCS).<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-collections.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-46574","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ambrogio Garden Machines - Lambrechts Tuinmachines<\/title>\n<meta name=\"description\" content=\"Ambrogio garden machines in Herent and Tienen, Belgium by Lambrechts Garden Machines.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ambrogio Garden Machines - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Ambrogio garden machines in Herent and Tienen, Belgium by Lambrechts Garden Machines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T15:02:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lambrechts-tuinmachines.be\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ambrogio Garden Machines - Lambrechts Tuinmachines","description":"Ambrogio garden machines in Herent and Tienen, Belgium by Lambrechts Garden Machines.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Ambrogio Garden Machines - Lambrechts Tuinmachines","og_description":"Ambrogio garden machines in Herent and Tienen, Belgium by Lambrechts Garden Machines.","og_url":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-08-13T15:02:18+00:00","og_image":[{"url":"https:\/\/lambrechts-tuinmachines.be\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/","url":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/","name":"Ambrogio Garden Machines - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/#primaryimage"},"image":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/#primaryimage"},"thumbnailUrl":"https:\/\/lambrechts-tuinmachines.be\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png","datePublished":"2025-07-28T14:12:56+00:00","dateModified":"2025-08-13T15:02:18+00:00","description":"Ambrogio garden machines in Herent and Tienen, Belgium by Lambrechts Garden Machines.","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/#primaryimage","url":"https:\/\/lambrechts-tuinmachines.be\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png","contentUrl":"https:\/\/lambrechts-tuinmachines.be\/wp-content\/uploads\/2025\/07\/ambrogio-category-image-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/ambrogio-garden-machines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Ambrogio Garden Machines"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/46574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/comments?post=46574"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/46574\/revisions"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=46574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}