{"id":36496,"date":"2025-05-28T10:01:25","date_gmt":"2025-05-28T10:01:25","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/our-brands\/"},"modified":"2025-07-29T17:07:30","modified_gmt":"2025-07-29T17:07:30","slug":"partners","status":"publish","type":"page","link":"https:\/\/lambrechts.designstudio.net\/en\/partners\/","title":{"rendered":"Brands"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-collections.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-36496","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brands - Lambrechts Tuinmachines<\/title>\n<meta name=\"description\" content=\"Partners Lambrechts Garden Machines | Buying, renting and garden machine maintenance. Herent and Tienen Belgium.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brands - Lambrechts Tuinmachines\" \/>\n<meta property=\"og:description\" content=\"Partners Lambrechts Garden Machines | Buying, renting and garden machine maintenance. Herent and Tienen Belgium.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/partners\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T17:07:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brands - Lambrechts Tuinmachines","description":"Partners Lambrechts Garden Machines | Buying, renting and garden machine maintenance. Herent and Tienen Belgium.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"Brands - Lambrechts Tuinmachines","og_description":"Partners Lambrechts Garden Machines | Buying, renting and garden machine maintenance. Herent and Tienen Belgium.","og_url":"https:\/\/lambrechts.designstudio.net\/en\/partners\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2025-07-29T17:07:30+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/partners\/","url":"https:\/\/lambrechts.designstudio.net\/en\/partners\/","name":"Brands - Lambrechts Tuinmachines","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"datePublished":"2025-05-28T10:01:25+00:00","dateModified":"2025-07-29T17:07:30+00:00","description":"Partners Lambrechts Garden Machines | Buying, renting and garden machine maintenance. Herent and Tienen Belgium.","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/partners\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/partners\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Brands"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/36496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/comments?post=36496"}],"version-history":[{"count":0,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/36496\/revisions"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=36496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}