{"id":1405,"date":"2025-05-21T09:05:44","date_gmt":"2025-05-21T09:05:44","guid":{"rendered":"https:\/\/lambrechts.designstudio.net\/stihl-en\/equipment-and-tools-en\/pruning-poles-pruning-sticks-en\/"},"modified":"2026-07-11T03:52:29","modified_gmt":"2026-07-11T03:52:29","slug":"pruning-poles-pruning-sticks-en","status":"publish","type":"page","link":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/","title":{"rendered":"Pruning poles \/ pruning sticks"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":43578,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1405","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STIHL Equipment and tools Pruning poles \/ pruning sticks<\/title>\n<meta name=\"description\" content=\"STIHL Pruning poles pruning sticks by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. For safe comfortable and effortless pruning up...\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STIHL Equipment and tools Pruning poles \/ pruning sticks\" \/>\n<meta property=\"og:description\" content=\"STIHL Pruning poles pruning sticks by Lambrechts Garden Machinery in Herent, Belgium &amp; Tienen, Belgium. For safe comfortable and effortless pruning up...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Lambrechts Tuinmachines\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:52:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STIHL Equipment and tools Pruning poles \/ pruning sticks","description":"STIHL Pruning poles pruning sticks by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. For safe comfortable and effortless pruning up...","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_GB","og_type":"article","og_title":"STIHL Equipment and tools Pruning poles \/ pruning sticks","og_description":"STIHL Pruning poles pruning sticks by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. For safe comfortable and effortless pruning up...","og_url":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/","og_site_name":"Lambrechts Tuinmachines","article_modified_time":"2026-07-11T03:52:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/","url":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/","name":"STIHL Equipment and tools Pruning poles \/ pruning sticks","isPartOf":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/#website"},"datePublished":"2025-05-21T09:05:44+00:00","dateModified":"2026-07-11T03:52:29+00:00","description":"STIHL Pruning poles pruning sticks by Lambrechts Garden Machinery in Herent, Belgium & Tienen, Belgium. For safe comfortable and effortless pruning up...","breadcrumb":{"@id":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/pruning-poles-pruning-sticks-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lambrechts.designstudio.net\/en\/"},{"@type":"ListItem","position":2,"name":"Sawing and Pruning","item":"https:\/\/lambrechts.designstudio.net\/en\/sawing-and-pruning-en\/"},{"@type":"ListItem","position":3,"name":"Pruning poles \/ pruning sticks"}]},{"@type":"WebSite","@id":"https:\/\/lambrechts.designstudio.net\/en\/#website","url":"https:\/\/lambrechts.designstudio.net\/en\/","name":"Landscaping Dealer","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lambrechts.designstudio.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/1405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":1,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/1405\/revisions"}],"predecessor-version":[{"id":74010,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/1405\/revisions\/74010"}],"up":[{"embeddable":true,"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/pages\/43578"}],"wp:attachment":[{"href":"https:\/\/lambrechts.designstudio.net\/en\/wp-json\/wp\/v2\/media?parent=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}